{"id":440,"date":"2026-06-30T19:06:06","date_gmt":"2026-06-30T17:06:06","guid":{"rendered":"https:\/\/erziehungshilfe-hamburg.de\/karriere\/?post_type=jobs&#038;p=440"},"modified":"2026-06-30T19:07:46","modified_gmt":"2026-06-30T17:07:46","slug":"verwaltungsfachkraft","status":"publish","type":"jobs","link":"https:\/\/erziehungshilfe-hamburg.de\/karriere\/verwaltungsfachkraft\/","title":{"rendered":"Verwaltungsfachkraft &#8211; Hamburg Bramfeld"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"default","_kad_post_title":"default","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"class_list":["post-440","jobs","type-jobs","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/erziehungshilfe-hamburg.de\/karriere\/wp-json\/wp\/v2\/jobs\/440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erziehungshilfe-hamburg.de\/karriere\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/erziehungshilfe-hamburg.de\/karriere\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/erziehungshilfe-hamburg.de\/karriere\/wp-json\/wp\/v2\/media?parent=440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}